{"id":53,"date":"2020-11-24T19:42:37","date_gmt":"2020-11-24T19:42:37","guid":{"rendered":"http:\/\/cadenbach.eu\/audio\/?page_id=53"},"modified":"2026-05-09T05:27:52","modified_gmt":"2026-05-09T05:27:52","slug":"imprint","status":"publish","type":"page","link":"https:\/\/cadenbach.eu\/audio\/imprint\/","title":{"rendered":"Imprint"},"content":{"rendered":"\n<p>HERAUSGEBER:<br>Cadenbach Audio<br>Sandra Cadenbach<br>Kuhweg 24<br>49152 Bad Essen<br>Fon: +49 (0) 174 755 8 733<br>Mail: hhc(via)cadenbach.audio<\/p>\n\n\n\n<p>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:<\/p>\n\n\n\n<p>DE300770703, StNr.: 65\/108\/08599<\/p>\n\n\n\n<p>Inhaltlich Verantwortlicher gem\u00e4\u00df \u00a7 6 MDStV:<br>Hans-Hartwig Cadenbach<\/p>\n\n\n\n<p>HAFTUNGSHINWEIS:<br>Alle Rechte vorbehalten. Die Informationen sind Eigentum der Firma Cadenbach Audio. Sie stellen die zum Zeitpunkt der Publikation jeweils neusten Informationen dar. Eine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, Richtigkeit und Vollst\u00e4ndigkeit der zur Verf\u00fcgung gestellten Informationen und Daten ist ausgeschlossen. Dies gilt ebenso f\u00fcr alle anderen Websites, auf die mittels eines Hyperlinks verwiesen wird. F\u00fcr den Inhalt solcher Sites ist die Firma Cadenbach Audio ebenfalls nicht verantwortlich.<br>Die Informationen auf den Webseiten stellen in keinem Fall rechtliche Zusicherungen dar. Die Firma Cadenbach Audio beh\u00e4lt sich das Recht vor, bei Bedarf \u00c4nderungen oder Erg\u00e4nzungen der bereitgestellten Informationen oder Daten durchzuf\u00fchren. Aus den hier beschriebenen Themenbereichen k\u00f6nnen keine Rechtsanspr\u00fcche abgeleitet werden. Angebote sind in allen Teilen unverbindlich.<br>Die Firma Cadenbach Audio haftet weder f\u00fcr direkte noch indirekte Sch\u00e4den, die durch die Nutzung der Informationen oder Daten entstehen, die auf dieser Website zu finden sind. Rechte und Pflichten zwischen der Firma Cadenbach Audio und dem Nutzer der Website oder Dritten bestehen nicht.<br>Die Inhalte der Firma Cadenbach Audio sind urheberrechtlich gesch\u00fctzt. Die Inhalte d\u00fcrfen weder ganz noch teilweise ohne vorherige schriftliche Genehmigung des Urhebers vervielf\u00e4ltigt und\/oder ver\u00f6ffentlicht oder in einem Informationssystem gespeichert werden.<br>S\u00e4mtliche Informationen oder Daten, ihre Nutzung sowie s\u00e4mtliches mit der Website der Firma Cadenbach Audio zusammenh\u00e4ngendes Tun, Dulden oder Unterlassen unterliegen ausschlie\u00dflich deutschem Recht, unter Ausschluss von internationalem Recht. Erf\u00fcllungsort und ausschlie\u00dflicher Gerichtsstand ist Osnabr\u00fcck.<\/p>\n\n\n\n<p><strong>DATENSCHUTZHINWEISE DER Firma Cadenbach Audio NACH EU-DSGVO<br>(STAND August 2019)<\/strong><\/p>\n\n\n\n<p><strong>1. Datenschutz auf einen Blick<\/strong><\/p>\n\n\n\n<p><strong>1.1 Allgemeine Hinweise<\/strong><\/p>\n\n\n\n<p>Als Anbieter dieser Internetseiten sind wir gesetzlich verpflichtet, Sie \u00fcber Zweck, Umfang und Art der der Erhebung und Verwendung Ihrer personenbezogenen Daten zu informieren. Bei weiteren Fragen d\u00fcrfen Sie sich selbstverst\u00e4ndlich jederzeit gerne an uns wenden. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen.<\/p>\n\n\n\n<p><strong>1.2 Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website<\/strong><\/p>\n\n\n\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Er ist Verantwortlicher gem\u00e4\u00df Art.4 Abs.7 EU-Datenschutzgrundverordnung (DSGVO). Seine Kontaktdaten k\u00f6nnen Sie weiter oben nachlesen.<\/p>\n\n\n\n<p><strong>1.3 Wie erfassen wir Ihre personenbezogenen Daten<\/strong><\/p>\n\n\n\n<p>Ihre personenbezogenen Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben oder uns per E-Mail oder sonstiger Kommunikation \u00fcbermitteln (z.B. Vor- und Zunamen, Anschrift, Telefonnummer, Mobilfunknummer, Faxnummer und E-Mailadresse).Andere Daten werden automatisch und bereits beim rein informatorischen Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n\n\n\n<p><strong>1.4 Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/p>\n\n\n\n<p>Wenn Sie mit uns Kontakt aufnehmen, erfolgt eine Speicherung Ihrer Nutzerangaben zur Bearbeitung der Anfrage sowie f\u00fcr den Fall, dass Anschlussfragen entstehen. Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden. Wir verarbeiten die vorab genannten personenbezogenen Daten im Einklang mit den Bestimmungen der EU-Datenschutz-Grundverordnung (DSGVO) und dem Bundesdatenschutzgesetz (BDSG).<\/p>\n\n\n\n<p><strong>1.5 Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><\/p>\n\n\n\n<p>Sie haben uns gegen\u00fcber folgende Rechte hinsichtlich der Sie betreffenden personenbezogenen Daten:<\/p>\n\n\n\n<p>Recht auf Auskunft (Artikel 15 DSGVO),<\/p>\n\n\n\n<p>Recht auf Berichtigung (Artikel 16 DSGVO) oder L\u00f6schung (Artikel 17 DSGVO),<\/p>\n\n\n\n<p>Recht auf Einschr\u00e4nkung der Verarbeitung (Artikel 18 DSGVO),<\/p>\n\n\n\n<p>Recht auf Widerspruch gegen die Verarbeitung (Artikel 21 DSGVO),<\/p>\n\n\n\n<p>Recht auf Daten\u00fcbertragbarkeit (Artikel 20 DSGVO)<\/p>\n\n\n\n<p>Wir weisen Sie darauf hin, dass beim Auskunftsrecht und beim L\u00f6schungsrecht Einschr\u00e4nkungen nach \u00a7\u00a7 34 und 35 BDSG bestehen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu (s. unten Ziffer 4.3).<\/p>\n\n\n\n<p><strong>2. Allgemeine Hinweise zum Datenschutz<\/strong><\/p>\n\n\n\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.Beim Besuch unserer Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit Cookies und mit sogenannten Analyseprogrammen. Die Analyse Ihres Surf-Verhaltens erfolgt in der Regel anonym; das Surf-Verhalten kann nicht zu Ihnen zur\u00fcckverfolgt werden. Sie k\u00f6nnen dieser Analyse widersprechen oder sie durch die Nichtbenutzung bestimmter Tools verhindern. Details und Widerspruchsm\u00f6glichkeiten hierzu entnehmen Sie unserer Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p><strong>3. Informationen gem\u00e4\u00df Art 13 Abs. 1 DSGVO<\/strong><\/p>\n\n\n\n<p>Transparenz ist ein Kernelement des Schutzes personenbezogener Daten. Diese Transparenz bezieht sich auf die planm\u00e4\u00dfige Datenverarbeitung genauso wie auf den Fall einer m\u00f6glichen Datenschutzverletzung. Die Betroffenen und in bestimmten F\u00e4llen wie einer Datenschutzpanne auch die zust\u00e4ndige Aufsichtsbeh\u00f6rde f\u00fcr den Datenschutz m\u00fcssen informiert werden bzw. k\u00f6nnen Informationen verlangen.<\/p>\n\n\n\n<p><strong>3.1 Hinweis zur verantwortlichen Stelle<\/strong><\/p>\n\n\n\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n\n\n\n<p>Cadenbach Audio, Hans-Hartwig Cadenbach, Kuhweg 24, D-49152 Bad Essen, Tel. +49 174 755 8 733<\/p>\n\n\n\n<p><strong>&nbsp;3.2 Hinweis zum Datenschutzbeauftragten der Firma Cadenbach Audio<\/strong><\/p>\n\n\n\n<p>Hans-Hartwig Cadenbach, Kuhweg 24, D-49152 Bad Essen, Tel. +49 174 755 8 733<\/p>\n\n\n\n<p><strong>3.3 Zwecke, f\u00fcr die die personenbezogenen Daten verarbeitet werden:<\/strong><\/p>\n\n\n\n<p><strong>3.3.1&nbsp;Vertr\u00e4ge (Artikel 6 Abs.1 Buchst. b DSGVO)<\/strong><\/p>\n\n\n\n<p>Wir erheben, verarbeiten und nutzen personenbezogene Daten nur, soweit sie f\u00fcr die Begr\u00fcndung, inhaltliche Ausgestaltung oder \u00c4nderung des Rechtsverh\u00e4ltnisses erforderlich sind (Bestandsdaten). Dies erfolgt auf Grundlage von Art. 6 Abs. 1 Buchst. b) DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n\n\n\n<p>Personenbezogene Daten \u00fcber die Inanspruchnahme unserer Internetseiten (Nutzungsdaten) erheben, verarbeiten und nutzen wir nur, soweit dies erforderlich ist, um dem Nutzer die Inanspruchnahme des Dienstes zu erm\u00f6glichen oder abzurechnen.<\/p>\n\n\n\n<p>Die erhobenen Kundendaten werden nach Abschluss des Auftrags oder Beendigung der Gesch\u00e4ftsbeziehung gel\u00f6scht. Gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n\n\n\n<p>Wir \u00fcbermitteln personenbezogene Daten an Dritte nur dann, wenn dies im Rahmen der Vertragsabwicklung notwendig ist. Eine weitergehende \u00dcbermittlung der Daten erfolgt nicht bzw. nur dann, wenn Sie der \u00dcbermittlung ausdr\u00fccklich zugestimmt haben. Eine Weitergabe Ihrer Daten an Dritte ohne ausdr\u00fcckliche Einwilligung, etwa zu Zwecken der Werbung, erfolgt nicht.<\/p>\n\n\n\n<p><strong>3.3.2&nbsp; Berechtigte Interessen (Artikel 6 Abs. 1 Buchst. f DSGVO)<\/strong><\/p>\n\n\n\n<p>Sollte dies notwendig sein, verarbeiten wir Ihre personenbezogenen Daten \u00fcber die eigentliche Erf\u00fcllung des Vertrages hinaus zum Zwecke der Wahrung berechtigter Interessen von uns oder Dritten (z.B. Geltendmachung rechtlicher Anspr\u00fcche; Markt- und Meinungsforschung, soweit Sie der Nutzung Ihrer Daten nicht widersprochen haben; Risikosteuerung im Unternehmen; Gew\u00e4hrleistung der IT-Sicherheit und des IT-Betriebs).<\/p>\n\n\n\n<p><strong>3.3.3&nbsp; Gesetzl. Vorgaben, \u00f6ffentl. Interesse (Artikel 6 Abs.1 Buchst. c und e DSGVO)<\/strong><\/p>\n\n\n\n<p>Au\u00dferdem sind Verarbeitungszwecke unter anderem die Erf\u00fcllung steuerrechtlicher Kontroll- und Meldepflichten sowie die Bewertung und Steuerung von betrieblichen Risiken. Denn wir unterliegen gesetzlichen Anforderungen (z.B. Steuergesetzen).<\/p>\n\n\n\n<p><strong>3.4 Empf\u00e4nger der personenbezogenen Daten<\/strong><\/p>\n\n\n\n<p>Empf\u00e4nger sind Mitarbeiter, Vorgesetzte und Vertragspartner der Firma Cadenbach Audio. Weitere Empf\u00e4nger sind \u00f6ffentliche und nicht\u00f6ffentliche Stellen, denen die Daten auf Grund einer gesetzlichen oder vertragsrechtlichen Verpflichtung zur Verf\u00fcgung gestellt werden m\u00fcssen.<\/p>\n\n\n\n<p>In L\u00e4nder au\u00dferhalb der EU bzw. des EWR (sogenannte Drittstaaten) werden personenbezogene Daten nur insoweit \u00fcbermittelt, als dies zur Erf\u00fcllung von vertraglichen und gesetzlichen Pflichten notwendig ist oder im Rahmen einer Auftragsdatenverarbeitung. Werden Dienstleister im Drittstaat eingesetzt, sind diese zus\u00e4tzlich zu schriftlichen Weisungen durch die Vereinbarung der EU-Standardvertragsklauseln zur Einhaltung des Datenschutzniveaus in Europa verpflichtet.<\/p>\n\n\n\n<p><strong>3.5 Rechtsgrundlagen der Datenerhebung, -speicherung und -verarbeitung<\/strong><\/p>\n\n\n\n<p>Soweit wir f\u00fcr Verarbeitungsvorg\u00e4nge personenbezogener Daten eine Einwilligung der betroffenen Person einholen, dient Artikel 6 Absatz 1 Buchst. a EU Datenschutz-Grundverordnung (DSGVO) als Rechtsgrundlage.<\/p>\n\n\n\n<p>Im \u00dcbrigen wird auf die Angaben in Ziffer 3.3 verwiesen.<\/p>\n\n\n\n<p><strong>4. Informationen gem\u00e4\u00df Art 13 Abs. 2 DSGVO<\/strong><\/p>\n\n\n\n<p><strong>4.1 Dauer der Speicherung<\/strong><\/p>\n\n\n\n<p>Wenn bei der Erhebung personenbezogener Daten (z.B. aufgrund einer Einwilligung) keine ausdr\u00fcckliche Speicherdauer angegeben wird, verarbeiten und speichern wir personenbezogene Daten der betroffenen Person nur solange, wie dies zur Erreichung des Speicherungszwecks erforderlich ist. Eine Speicherung&nbsp; \u00fcber diesen Zeitraum hinaus&nbsp; erfolgt, soweit gesetzliche Aufbewahrungsfristen bestehen, dies also durch den europ\u00e4ischen oder nationalen Gesetzgeber in unionsrechtlichen Verordnungen, Gesetzen oder sonstigen Vorschriften, denen der f\u00fcr die Verarbeitung verantwortliche unterliegt, vorgesehen wurde.<\/p>\n\n\n\n<p><strong>4.2 Rechte der Betroffenen<\/strong><\/p>\n\n\n\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit die oben in Ziffer 1.5 genannten Rechte. Wegen des Inhalts dieser Rechte verweisen wir insbesondere auf&nbsp;<strong>Artikel 15 bis 18<\/strong>sowie&nbsp;<strong>Artikel 20 bis 21<\/strong>der Datenschutzgrundverordnung [Verordnung (EU) 2016\/679 des Europ\u00e4ischen Parlaments und des Rates vom 27. April 2016 zum Schutz nat\u00fcrlicher Personen bei der Verarbeitung personenbezogener Daten, zum freien Datenverkehr und zur Aufhebung der Richtlinie 95\/46\/EG]. Den Text der Verordnung finden Sie unter nachstehendem Link:<a href=\"https:\/\/eur-lex.europa.eu\/legal%20content\/DE\/TXT\/HTML\/?uri=OJ:L:2016:119:FULL&amp;from=DE\">https:\/\/eur-lex.europa.eu\/legal content\/DE\/TXT\/HTML\/?uri=OJ:L:2016:119:FULL&amp;from=DE<\/a><\/p>\n\n\n\n<p><strong>4.3 Beschwerderecht<\/strong><\/p>\n\n\n\n<p>Im Falle datenschutzrechtlicher Verst\u00f6\u00dfe steht dem Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Datenschutzaufsichtsbeh\u00f6rde zu. Deren Daten lauten wie folgt:<\/p>\n\n\n\n<p>Landesbeauftragte f\u00fcr Datenschutz und Informationsfreiheit Niedersachsen<\/p>\n\n\n\n<p>Barbara Thiel<br>Die Landesbeauftragte f\u00fcr den Datenschutz Niedersachsen<br>Prinzenstra\u00dfe 5<br>30159 Hannover<\/p>\n\n\n\n<p>Telefon 0511-120 4500<\/p>\n\n\n\n<p>Fax 0511-120 4599<\/p>\n\n\n\n<p>Homepage:&nbsp;<a href=\"https:\/\/www.lfd.niedersachsen.de\/\">https:\/\/lfd.niedersachsen.de<\/a><\/p>\n\n\n\n<p><strong>4.4 Widerspruch oder Widerruf gegen die Verarbeitung Ihrer Daten<\/strong><\/p>\n\n\n\n<p><strong>4.4.1 &nbsp;Widerruf der Einwilligung<\/strong><\/p>\n\n\n\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an: hhcadenbach<a>@rheintec.de&nbsp;<\/a>Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf&nbsp;unber\u00fchrt.<\/p>\n\n\n\n<p><strong>4.4.2&nbsp; Interessensabw\u00e4gung<\/strong><\/p>\n\n\n\n<p>Soweit wir die Verarbeitung Ihrer personenbezogenen Daten auf die Interessenabw\u00e4gung st\u00fctzen, k\u00f6nnen Sie Widerspruch gegen die Verarbeitung einlegen. Dies ist der Fall, wenn die Verarbeitung insbesondere nicht zur Erf\u00fcllung eines Vertrags mit Ihnen erforderlich ist, was von uns jeweils bei der nachfolgenden Beschreibung der Funktionen dargestellt wird. Bei Aus\u00fcbung eines solchen Widerspruchs bitten wir um Darlegung der Gr\u00fcnde, weshalb wir Ihre personenbezogenen Daten nicht wie von uns durchgef\u00fchrt verarbeiten sollten. Im Falle Ihres begr\u00fcndeten Widerspruchs pr\u00fcfen wir die Sachlage und werden entweder die Datenverarbeitung einstellen bzw. anpassen oder Ihnen unsere zwingenden schutzw\u00fcrdigen Gr\u00fcnde aufzeigen, aufgrund derer wir die Verarbeitung fortf\u00fchren. Der Widerspruch ist an unseren Datenschutzbeauftragten (siehe oben Ziffer 3.3) zu richten.<\/p>\n\n\n\n<p><strong>4.4.3&nbsp; Automatisierte&nbsp; Verfahren (Profiling)<\/strong><\/p>\n\n\n\n<p>Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht. Widersprechen Sie der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so werden die Sie betreffenden personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeitet. Sie haben die M\u00f6glichkeit, im Zusammenhang mit der Nutzung von Diensten der Informationsgesellschaft Ihr Widerspruchsrecht mittels automatisierter Verfahren auszu\u00fcben, bei denen technische Spezifikationen verwendet werden. Der Widerspruch ist an unseren Datenschutzbeauftragten (siehe oben Ziffer 3.3) zu richten.<\/p>\n\n\n\n<p><strong>5. Verschl\u00fcsselung<\/strong><\/p>\n\n\n\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile. Wenn die SSL-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n\n\n\n<p><strong>6. Widerspruch des Betreibers dieser Website gegen Werbe-Mails<\/strong><\/p>\n\n\n\n<p>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n\n\n\n<p><strong>7. Datenerfassung auf unserer Website<\/strong><\/p>\n\n\n\n<p><strong>7.1 Cookies<\/strong><\/p>\n\n\n\n<p>Die Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert. Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/p>\n\n\n\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n\n\n\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 Buchst. f DSGVO gespeichert. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Soweit andere Cookies (z.B. Cookies zur Analyse Ihres Surfverhaltens) gespeichert werden, werden diese in dieser Datenschutzerkl\u00e4rung gesondert behandelt.<\/p>\n\n\n\n<p><strong>7.2 Server-Log-Dateien<\/strong><\/p>\n\n\n\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n\n\n\n<p>Browsertyp und Browserversion<\/p>\n\n\n\n<p>verwendetes Betriebssystem<\/p>\n\n\n\n<p>Referrer URL<\/p>\n\n\n\n<p>Hostname des zugreifenden Rechners<\/p>\n\n\n\n<p>Uhrzeit der Serveranfrage<\/p>\n\n\n\n<p>IP-Adresse<\/p>\n\n\n\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n\n\n\n<p>Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 Buchst. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n\n\n\n<p><strong>7.3 Kontaktformular<\/strong><\/p>\n\n\n\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p>Die Verarbeitung der in das Kontaktformular eingegebenen Daten erfolgt somit ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 Buchst. a DSGVO), die wir bei Ihnen mittels einer OptIn Zustimmung bei Ihnen abfragen. Sie k\u00f6nnen diese Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an unseren Datenschutzbeauftragten (Adresse siehe oben 3.2). Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<p><strong>8. Google<\/strong><strong>Analytics<\/strong><\/p>\n\n\n\n<p>Diese Website nutzt Funktionen des Webanalysedienstes Google Analytics. Anbieter ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Ireland.<\/p>\n\n\n\n<p>Google Analytics verwendet so genannte \u201cCookies\u201d. Das sind Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Die Speicherung von Google-Analytics-Cookies erfolgt auf Grundlage von Art. 6 Abs. 1 Buchst. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren. Google \u00fcbermittelt die Daten Dritten nur im Rahmen gesetzlicher Vorschriften oder im Rahmen einer Auftragsdatenverarbeitung. Google wird die erfassten Daten nicht mit anderen von Google erfassten Daten kombinieren.<\/p>\n\n\n\n<p>Google Analytics wird bei uns mit der Erweiterung \u201canonymizeIp()\u201d eingesetzt. Dadurch wird Ihre IP-Adresse von Google innerhalb von Mitgliedstaaten der EU oder in anderen EWR-Vertragsstaaten vor der \u00dcbermittlung in die USA gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die komplette IP-Adresse an Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Google Inc. wird in unserem Auftrag diese Informationen benutzen, um die Nutzung der Website auszuwerten, um Berichte \u00fcber die Aktivit\u00e4ten auf der Website zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen.<\/p>\n\n\n\n<p>Sie k\u00f6nnen die Erfassung Ihrer Daten durch Google Analytics jederzeit verhindern, indem Sie auf einen bereitgestellten Opt-Out Link klicken. Hierbei wird ein Opt-Out-Cookie gesetzt, der die Erfassung Ihrer Daten bei zuk\u00fcnftigen Besuchen dieser Website verhindert.<\/p>\n\n\n\n<p>\u201eVerbiete Google Analytics, mich zu verfolgen\u201c<\/p>\n\n\n\n<p>Dar\u00fcber hinaus kann die Erfassung der durch das Cookie erzeugten und auf ihre Nutzung der Website bezogenen Daten an Google und die Verarbeitung dieser Daten durch Google Inc verhindert werden, indem das unter dem nachfolgenden Link verf\u00fcgbare Browser \u2013 Plugin heruntergeladen und installiert wird:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttp:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\n<\/div><\/figure>\n\n\n\n<p>Mehr Informationen zum Umgang mit Nutzerdaten bei Google Analytics finden Sie in der Datenschutzerkl\u00e4rung von Google:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\n<\/div><\/figure>\n\n\n\n<p><strong>9. Hinweise zu sozialen Netzwerken<\/strong><\/p>\n\n\n\n<p>Unser Internetauftritt verwendet in Zukunft m\u00f6glicherweise direkte Link-Verbindungen der sozialen Netzwerke<\/p>\n\n\n\n<p>facebook.com &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Ireland<\/p>\n\n\n\n<p>LinkedIn.com &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; LinkedIn Ireland Unlimited Company Wilton Place, Dublin 2, Irland<\/p>\n\n\n\n<p>Instagram.com&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Instagram LLC Vertreten durch Kevin Systrom und Mike Krieger,1601 Willow Rd Menlo Park CA 94025 USA<\/p>\n\n\n\n<p>xing.com &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; XING AG, G\u00e4nsemarkt 43, 20354 Hamburg, Deutschland, \u201cXing\u201d<\/p>\n\n\n\n<p>Die Direkt-Links sind mit dem jeweiligen Logo des sozialen Netzwerkes gekennzeichnet. \u00dcblicherweise bauen diese Direkt-Links umgehend eine direkte Verbindung zu den Servern der sozialen Netzwerke auf, sobald Sie das jeweilige Logo aktivieren. Durch die Aktivierung der Direkt-Links durch den Besucher unserer Internetseiten erhalten die sozialen Netzwerke die Information, dass Sie die entsprechende Seite unseres Internetauftritts aufgerufen haben. Sind Sie bei dem entsprechenden sozialen Netzwerk angemeldet, kann das soziale Netzwerk den Besuch Ihrem Profil-Konto zuordnen. Wenn Sie mit den Direkt-Links interagieren, wird die entsprechende Information von Ihrem Browser direkt an das soziale Netzwerk \u00fcbermittelt und dort gespeichert.<\/p>\n\n\n\n<p>Zweck und Umfang der Datenerhebung und die weitere Verarbeitung und Nutzung der Daten durch das soziale Netzwerk sowie Ihre diesbez\u00fcglichen Rechte und Einstellungen zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen der sozialen Netzwerke:<\/p>\n\n\n\n<p>Datenschutzhinweise Facebook<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/de-de.facebook.com\/privacy\/explanation\n<\/div><\/figure>\n\n\n\n<p>Datenschutzhinweise linkedin<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.linkedin.com\/legal\/privacy-policy?trk=hb_ft_priv\n<\/div><\/figure>\n\n\n\n<p>Datenschutzhinweise&nbsp; Instagram:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/help.instagram.com\/519522125107875?helpref=page_content\n<\/div><\/figure>\n\n\n\n<p>Datenschutzhinweise von Xing<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/privacy.xing.com\/de\/datenschutzerklaerung\n<\/div><\/figure>\n\n\n\n<p><strong>10. Google AdWords und Google Conversion-Tracking<\/strong><\/p>\n\n\n\n<p>Diese Website verwendet Google AdWords. AdWords ist ein Online-Werbeprogramm der Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, United States (\u201cGoogle\u201d). Im Rahmen von Google AdWords nutzen wir das so genannte Conversion-Tracking. Wenn Sie auf eine von Google geschaltete Anzeige klicken wird ein Cookie f\u00fcr das Conversion-Tracking gesetzt. Bei Cookies handelt es sich um kleine Textdateien, die der Internet- Browser auf dem Computer des Nutzers ablegt. Diese Cookies verlieren nach 30 Tagen ihre G\u00fcltigkeit und dienen nicht der pers\u00f6nlichen Identifizierung der Nutzer. Besucht der Nutzer bestimmte Seiten dieser Website und das Cookie ist noch nicht abgelaufen, k\u00f6nnen Google und wir erkennen, dass der Nutzer auf die Anzeige geklickt hat und zu dieser Seite weitergeleitet wurde. Jeder Google AdWords-Kunde erh\u00e4lt ein anderes Cookie. Die Cookies k\u00f6nnen nicht \u00fcber die Websites von Ad Words \u2013 Kunden nachverfolgt werden. Die mithilfe des Conversion-Cookies eingeholten Informationen dienen dazu, Conversion-Statistiken f\u00fcr AdWords-Kunden zu erstellen, die sich f\u00fcr Conversion-Tracking entschieden haben.<\/p>\n\n\n\n<p>Die Kunden erfahren die Gesamtanzahl der Nutzer, die auf ihre Anzeige geklickt haben und zu einer mit einem Conversion-Tracking-Tag versehenen Seite weitergeleitet wurden. Sie erhalten jedoch keine Informationen, mit denen sich Nutzer pers\u00f6nlich identifizieren lassen. Wenn Sie nicht am Tracking teilnehmen m\u00f6chten, k\u00f6nnen Sie dieser Nutzung widersprechen, indem Sie das Cookie des Google Conversion-Trackings \u00fcber ihren Internet-Browser unter Nutzereinstellungen leicht deaktivieren. Sie werden sodann nicht in die Conversion-Tracking Statistiken aufgenommen.<\/p>\n\n\n\n<p>Die Speicherung von \u201cConversion- Cookies\u201d erfolgt auf Grundlage von Art. 6 Abs. 1 Buchst. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren.<\/p>\n\n\n\n<p>Mehr Informationen zu Google AdWords und Google Conversion-Tracking finden Sie in den Datenschutzbestimmungen von Google:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.google.de\/policies\/privacy\n<\/div><\/figure>\n\n\n\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n\n\n\n<p>Deaktivieren: Blockieren von Cookies der Domain \u201cgoogleadservices.com\u201d<\/p>\n\n\n\n<p><strong>11. Elektronische Post (E-Mail)<\/strong><\/p>\n\n\n\n<p>Wenn Sie uns eine E-Mail senden, wird diese von uns bis zur Erledigung Ihrer Anfrage bzw. bis zum Ablauf etwaiger gesetzlicher Aufbewahrungspflichten gespeichert. Wir tragen Sorge daf\u00fcr, dass die Daten vor der unberechtigten Kenntnisnahme Dritter gesichert aufbewahrt werden. Beachten Sie jedoch bitte, dass unverschl\u00fcsselte E-Mails, die \u00fcber das Internet versendet werden, nicht hinreichend vor der unbefugten Kenntnisnahme durch Dritte gesch\u00fctzt sind.<\/p>\n\n\n\n<p>Informationen, die Sie unverschl\u00fcsselt per elektronische Post (E-Mail) an uns senden, k\u00f6nnen m\u00f6glicherweise auf dem \u00dcbertragungsweg von Dritten gelesen werden. Wir k\u00f6nnen in der Regel auch Ihre Identit\u00e4t nicht \u00fcberpr\u00fcfen und wissen nicht, wer sich hinter einer E-Mail-Adresse verbirgt. Eine rechtssichere Kommunikation durch einfache E-Mail ist daher nicht gew\u00e4hrleistet. Wir setzen \u2013 wie viele E-Mail-Anbieter \u2013 Filter gegen unerw\u00fcnschte Werbung (\u201eSPAM-Filter\u201c) ein, die in seltenen F\u00e4llen auch normale E-Mails f\u00e4lschlicherweise automatisch als unerw\u00fcnschte Werbung einordnen und l\u00f6schen. E-Mails, die sch\u00e4digende Programme (\u201eViren\u201c) enthalten, werden von uns in jedem Fall automatisch gel\u00f6scht.<\/p>\n\n\n\n<p><strong>12. Schlussbestimmung<\/strong><\/p>\n\n\n\n<p>Um der stetigen Entwicklung des Internets gerecht zu werden, kann die Firma Cadenbach Audio diese Datenschutzhinweise jederzeit unter Beachtung der jeweils aktuellen datenschutzrechtlichen Vorgaben anpassen.<\/p>\n\n\n\n<p><strong>Cadenbach Audio<\/strong><\/p>\n\n\n\n<p><strong>Im November 2020<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HERAUSGEBER:Cadenbach AudioSandra CadenbachKuhweg 2449152 Bad EssenFon: +49 (0) 174 755 8 733Mail: hhc(via)cadenbach.audio Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz: DE300770703, StNr.: 65\/108\/08599 Inhaltlich Verantwortlicher gem\u00e4\u00df <a href=\"https:\/\/cadenbach.eu\/audio\/imprint\/\" class=\"btn btn-link continue-link\">Continue Reading<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-53","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/pages\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":3,"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/pages\/53\/revisions"}],"predecessor-version":[{"id":884,"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/pages\/53\/revisions\/884"}],"wp:attachment":[{"href":"https:\/\/cadenbach.eu\/audio\/wp-json\/wp\/v2\/media?parent=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}